{"id":2905,"date":"2025-12-28T02:53:00","date_gmt":"2025-12-27T18:53:00","guid":{"rendered":"https:\/\/deyeess.com\/product\/se-f16-max\/"},"modified":"2026-03-24T00:26:15","modified_gmt":"2026-03-23T16:26:15","slug":"se-f16-max","status":"publish","type":"product","link":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/","title":{"rendered":"SE-F16 Max"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-center\">\u30b9\u30de\u30fc\u30c8\u30a8\u30cd\u30eb\u30ae\u30fc\u304c\u3042\u306a\u305f\u306e\u5bb6\u3092\u3069\u306e\u3088\u3046\u306b\u52d5\u304b\u3059\u304b\uff1f<\/h2>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-video product-detail-banner\"><video height=\"720\" style=\"aspect-ratio: 1280 \/ 720;\" width=\"1280\" controls poster=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/Deye-SE-F-Series-Product-Video-0829-720p.webp\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/Deye-SE-F-Series-Product-Video-0829-720p.mp4\"><\/video><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">\u5f53\u793e\u306e\u5bb6\u5ead\u7528\u30a8\u30cd\u30eb\u30ae\u30fc\u8caf\u8535\u304c\u512a\u308c\u3066\u3044\u308b\u7406\u7531\u306f\uff1f<\/h2>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-rib-theme-responsive-image  \"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-1.webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-1.webp\"><img decoding=\"async\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-1.webp\" alt=\"\" class=\"rib-theme-image\" loading=\"lazy\"><\/picture><\/div>\n\n<div class=\"wp-block-rib-theme-responsive-image  \"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-2.webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-2.webp\"><img decoding=\"async\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-2.webp\" alt=\"\" class=\"rib-theme-image\" loading=\"lazy\"><\/picture><\/div>\n\n<div class=\"wp-block-rib-theme-responsive-image  \"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-3.webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-3.webp\"><img decoding=\"async\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-3.webp\" alt=\"\" class=\"rib-theme-image\" loading=\"lazy\"><\/picture><\/div>\n\n<div class=\"wp-block-rib-theme-responsive-image  \"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-4.webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-4.webp\"><img decoding=\"async\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-4.webp\" alt=\"\" class=\"rib-theme-image\" loading=\"lazy\"><\/picture><\/div>\n\n<div class=\"wp-block-rib-theme-responsive-image  \"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-5.webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-5.webp\"><img decoding=\"async\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-5.webp\" alt=\"\" class=\"rib-theme-image\" loading=\"lazy\"><\/picture><\/div>\n\n<div class=\"wp-block-rib-theme-responsive-image  \"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-6.webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-6.webp\"><img decoding=\"async\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-6.webp\" alt=\"\" class=\"rib-theme-image\" loading=\"lazy\"><\/picture><\/div>\n\n<div class=\"wp-block-rib-theme-responsive-image  \"><picture><source media=\"(max-width: 767px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-7.webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-7.webp\"><img decoding=\"async\" src=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/SE-F16-Max-ja-7.webp\" alt=\"\" class=\"rib-theme-image\" loading=\"lazy\"><\/picture><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30b9\u30de\u30fc\u30c8\u30a8\u30cd\u30eb\u30ae\u30fc\u304c\u3042\u306a\u305f\u306e\u5bb6\u3092\u3069\u306e\u3088\u3046\u306b\u52d5\u304b\u3059\u304b\uff1f \u5f53\u793e\u306e\u5bb6\u5ead\u7528\u30a8\u30cd\u30eb\u30ae\u30fc\u8caf\u8535\u304c\u512a\u308c\u3066\u3044\u308b\u7406\u7531\u306f\uff1f<\/p>\n","protected":false},"featured_media":2906,"template":"","meta":{"_acf_changed":false},"product-application":[70],"product_brand":[],"product_cat":[58],"product_tag":[],"class_list":{"0":"post-2905","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product-application-residential-ess","7":"product_cat-spring","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SE-F16 Max - Deye ESS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SE-F16 Max - Deye ESS\" \/>\n<meta property=\"og:description\" content=\"\u30b9\u30de\u30fc\u30c8\u30a8\u30cd\u30eb\u30ae\u30fc\u304c\u3042\u306a\u305f\u306e\u5bb6\u3092\u3069\u306e\u3088\u3046\u306b\u52d5\u304b\u3059\u304b\uff1f \u5f53\u793e\u306e\u5bb6\u5ead\u7528\u30a8\u30cd\u30eb\u30ae\u30fc\u8caf\u8535\u304c\u512a\u308c\u3066\u3044\u308b\u7406\u7531\u306f\uff1f\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/\" \/>\n<meta property=\"og:site_name\" content=\"Deye ESS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T16:26:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/se-f16-max-thumb.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/\",\"url\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/\",\"name\":\"SE-F16 Max - Deye ESS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deyeess.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/se-f16-max-thumb.webp\",\"datePublished\":\"2025-12-27T18:53:00+00:00\",\"dateModified\":\"2026-03-23T16:26:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deyeess.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/se-f16-max-thumb.webp\",\"contentUrl\":\"https:\\\/\\\/deyeess.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/se-f16-max-thumb.webp\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/product\\\/se-f16-max\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30b7\u30e7\u30c3\u30d7\",\"item\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SE-F16 Max\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/\",\"name\":\"Deye ESS\",\"description\":\"To make ESS Better Powering Your Life\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deyeess.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SE-F16 Max - Deye ESS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/","og_locale":"ja_JP","og_type":"article","og_title":"SE-F16 Max - Deye ESS","og_description":"\u30b9\u30de\u30fc\u30c8\u30a8\u30cd\u30eb\u30ae\u30fc\u304c\u3042\u306a\u305f\u306e\u5bb6\u3092\u3069\u306e\u3088\u3046\u306b\u52d5\u304b\u3059\u304b\uff1f \u5f53\u793e\u306e\u5bb6\u5ead\u7528\u30a8\u30cd\u30eb\u30ae\u30fc\u8caf\u8535\u304c\u512a\u308c\u3066\u3044\u308b\u7406\u7531\u306f\uff1f","og_url":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/","og_site_name":"Deye ESS","article_modified_time":"2026-03-23T16:26:15+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/se-f16-max-thumb.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/","url":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/","name":"SE-F16 Max - Deye ESS","isPartOf":{"@id":"https:\/\/deyeess.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/#primaryimage"},"image":{"@id":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/#primaryimage"},"thumbnailUrl":"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/se-f16-max-thumb.webp","datePublished":"2025-12-27T18:53:00+00:00","dateModified":"2026-03-23T16:26:15+00:00","breadcrumb":{"@id":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deyeess.com\/ja\/product\/se-f16-max\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/#primaryimage","url":"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/se-f16-max-thumb.webp","contentUrl":"https:\/\/deyeess.com\/wp-content\/uploads\/2025\/12\/se-f16-max-thumb.webp","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/deyeess.com\/ja\/product\/se-f16-max\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/deyeess.com\/ja\/home\/"},{"@type":"ListItem","position":2,"name":"\u30b7\u30e7\u30c3\u30d7","item":"https:\/\/deyeess.com\/ja\/products\/"},{"@type":"ListItem","position":3,"name":"SE-F16 Max"}]},{"@type":"WebSite","@id":"https:\/\/deyeess.com\/ja\/#website","url":"https:\/\/deyeess.com\/ja\/","name":"Deye ESS","description":"To make ESS Better Powering Your Life","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deyeess.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/product\/2905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/media\/2906"}],"wp:attachment":[{"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/media?parent=2905"}],"wp:term":[{"taxonomy":"product-application","embeddable":true,"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/product-application?post=2905"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/product_brand?post=2905"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/product_cat?post=2905"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deyeess.com\/ja\/wp-json\/wp\/v2\/product_tag?post=2905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}